{"id":28892,"date":"2026-05-08T14:09:41","date_gmt":"2026-05-08T13:09:41","guid":{"rendered":"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/"},"modified":"2026-05-08T14:09:41","modified_gmt":"2026-05-08T13:09:41","slug":"magazijnmedewerker","status":"publish","type":"application","link":"https:\/\/eu-people.com\/pl\/job-offers\/magazijnmedewerker\/","title":{"rendered":"Magazijnmedewerker"},"content":{"rendered":"<p><strong>Wat ga je doen?<\/strong><\/p><p>Als Warehouse Worker \/ Unloader zorg jij ervoor dat pakketten veilig en effici\u00ebnt worden geladen en gelost. Je werkt met een slim transportsysteem waardoor het werk minder zwaar is dan je misschien denkt.<\/p><p><br><\/p><p><strong>Jouw werkzaamheden:<\/strong><\/p><p><span style=\"font-family: Symbol\">\u00b7<\/span><span style=\"font-size: 7pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span>Pakketten uit vrachtwagens lossen op de transportband <\/p><p><span style=\"font-family: Symbol\">\u00b7<\/span><span style=\"font-size: 7pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span>Pakketten vanaf de transportband in vrachtwagens laden <\/p><p><span style=\"font-family: Symbol\">\u00b7<\/span><span style=\"font-size: 7pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span>Samenwerken met collega\u2019s om het proces soepel te laten verlopen <\/p><p><span style=\"font-family: Symbol\">\u00b7<\/span><span style=\"font-size: 7pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span>Tillen van zware pakketten (tot 30 kg), bij zware pakketten krijg je hulp van collega\u2019s <\/p><p><span style=\"font-family: Symbol\">\u00b7<\/span><span style=\"font-size: 7pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span>Werken in een 3-ploegendienst<\/p><p><br><\/p><p>Geen ervaring? Geen probleem! Je krijgt duidelijke uitleg en begeleiding tijdens het werk.\u00a0<\/p><p><br><\/p><p><strong>Werktijden<\/strong><\/p><p>Je werkt in wisselende diensten:<\/p><p><br><\/p><p><span style=\"font-family: Symbol\">\u00b7<\/span><span style=\"font-size: 7pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><strong>Shift 1:<\/strong> 13:00 \u2013 22:30 <\/p><p><span style=\"font-family: Symbol\">\u00b7<\/span><span style=\"font-size: 7pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><strong>Shift 2:<\/strong> 19:30 \u2013 04:00 <\/p><p><span style=\"font-family: Symbol\">\u00b7<\/span><span style=\"font-size: 7pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><strong>Shift 3:<\/strong> 22:00 \u2013 06:00\u00a0<\/p><p><br><\/p>","protected":false},"author":0,"featured_media":0,"menu_order":0,"template":"","categories":[],"tigris_bedrijfstak":[116],"tigris_branche":[132],"tigris_dienstverband":[149],"tigris_opleidingsniveau":[125],"tigris_plaats":[142],"tigris_uren":[153],"class_list":["post-28892","application","type-application","status-publish","hentry","tigris_bedrijfstak-maak-een-keuze","tigris_branche-logistics","tigris_dienstverband-vast","tigris_opleidingsniveau-no-prior-education","tigris_plaats-oirschot","tigris_uren-39-00","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Magazijnmedewerker - EU-People | Profs for Profs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu-people.com\/pl\/job-offers\/magazijnmedewerker\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Magazijnmedewerker\" \/>\n<meta property=\"og:description\" content=\"Wat ga je doen?Als Warehouse Worker \/ Unloader zorg jij ervoor dat pakketten veilig en effici\u00ebnt worden geladen en gelost. Je werkt met een slim transportsysteem waardoor het werk minder zwaar is dan je misschien denkt.Jouw werkzaamheden:\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pakketten uit vrachtwagens lossen op de transportband \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pakketten vanaf de transportband in vrachtwagens laden \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Samenwerken met collega\u2019s om het&hellip; Czytaj dalej Magazijnmedewerker\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu-people.com\/pl\/job-offers\/magazijnmedewerker\/\" \/>\n<meta property=\"og:site_name\" content=\"EU-People | Profs for Profs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EUpeopleHQ\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/\",\"url\":\"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/\",\"name\":\"Magazijnmedewerker - EU-People | Profs for Profs\",\"isPartOf\":{\"@id\":\"https:\/\/eu-people.com\/pl\/#website\"},\"datePublished\":\"2026-05-08T13:09:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eu-people.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magazijnmedewerker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eu-people.com\/pl\/#website\",\"url\":\"https:\/\/eu-people.com\/pl\/\",\"name\":\"EU-People | Profs for Profs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eu-people.com\/pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eu-people.com\/pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eu-people.com\/pl\/#organization\",\"name\":\"EU-People | Profs for Profs\",\"url\":\"https:\/\/eu-people.com\/pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/eu-people.com\/pl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eu-people.com\/wp-content\/uploads\/2022\/01\/logo-alt.svg\",\"contentUrl\":\"https:\/\/eu-people.com\/wp-content\/uploads\/2022\/01\/logo-alt.svg\",\"width\":956,\"height\":354,\"caption\":\"EU-People | Profs for Profs\"},\"image\":{\"@id\":\"https:\/\/eu-people.com\/pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EUpeopleHQ\/\",\"https:\/\/www.instagram.com\/eupeople_jobs\/\",\"https:\/\/www.linkedin.com\/company\/eu-people-b.v.\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Magazijnmedewerker - EU-People | Profs for Profs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu-people.com\/pl\/job-offers\/magazijnmedewerker\/","og_locale":"pl_PL","og_type":"article","og_title":"Magazijnmedewerker","og_description":"Wat ga je doen?Als Warehouse Worker \/ Unloader zorg jij ervoor dat pakketten veilig en effici\u00ebnt worden geladen en gelost. Je werkt met een slim transportsysteem waardoor het werk minder zwaar is dan je misschien denkt.Jouw werkzaamheden:\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pakketten uit vrachtwagens lossen op de transportband \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pakketten vanaf de transportband in vrachtwagens laden \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Samenwerken met collega\u2019s om het&hellip; Czytaj dalej Magazijnmedewerker","og_url":"https:\/\/eu-people.com\/pl\/job-offers\/magazijnmedewerker\/","og_site_name":"EU-People | Profs for Profs","article_publisher":"https:\/\/www.facebook.com\/EUpeopleHQ\/","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/","url":"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/","name":"Magazijnmedewerker - EU-People | Profs for Profs","isPartOf":{"@id":"https:\/\/eu-people.com\/pl\/#website"},"datePublished":"2026-05-08T13:09:41+00:00","breadcrumb":{"@id":"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eu-people.com\/job-offers\/magazijnmedewerker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu-people.com\/"},{"@type":"ListItem","position":2,"name":"Magazijnmedewerker"}]},{"@type":"WebSite","@id":"https:\/\/eu-people.com\/pl\/#website","url":"https:\/\/eu-people.com\/pl\/","name":"EU-People | Profs for Profs","description":"","publisher":{"@id":"https:\/\/eu-people.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu-people.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/eu-people.com\/pl\/#organization","name":"EU-People | Profs for Profs","url":"https:\/\/eu-people.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/eu-people.com\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/eu-people.com\/wp-content\/uploads\/2022\/01\/logo-alt.svg","contentUrl":"https:\/\/eu-people.com\/wp-content\/uploads\/2022\/01\/logo-alt.svg","width":956,"height":354,"caption":"EU-People | Profs for Profs"},"image":{"@id":"https:\/\/eu-people.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EUpeopleHQ\/","https:\/\/www.instagram.com\/eupeople_jobs\/","https:\/\/www.linkedin.com\/company\/eu-people-b.v.\/"]}]}},"_links":{"self":[{"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/application\/28892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/application"}],"about":[{"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/types\/application"}],"version-history":[{"count":0,"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/application\/28892\/revisions"}],"wp:attachment":[{"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/media?parent=28892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/categories?post=28892"},{"taxonomy":"tigris_bedrijfstak","embeddable":true,"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/tigris_bedrijfstak?post=28892"},{"taxonomy":"tigris_branche","embeddable":true,"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/tigris_branche?post=28892"},{"taxonomy":"tigris_dienstverband","embeddable":true,"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/tigris_dienstverband?post=28892"},{"taxonomy":"tigris_opleidingsniveau","embeddable":true,"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/tigris_opleidingsniveau?post=28892"},{"taxonomy":"tigris_plaats","embeddable":true,"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/tigris_plaats?post=28892"},{"taxonomy":"tigris_uren","embeddable":true,"href":"https:\/\/eu-people.com\/pl\/wp-json\/wp\/v2\/tigris_uren?post=28892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}